{"id":242,"date":"2011-02-17T14:48:35","date_gmt":"2011-02-17T14:48:35","guid":{"rendered":"http:\/\/danavonmach.de\/?p=242"},"modified":"2026-07-04T14:02:53","modified_gmt":"2026-07-04T14:02:53","slug":"stimme-20","status":"publish","type":"post","link":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/","title":{"rendered":"Stimme 20"},"content":{"rendered":"<p><span class=\"testimonial-nr\">20<\/span>Hello Dana,\u2028 since the 03.11.I have been working as a clerk in the Neatherlands. .\u2028I enjoy my job as well as working with my colleagues, who support me whereever needed. The English course was for me beneficial, too, since I use it in my job, both in spoken and even more so written form.\u00a0 I enjoyed the course very much and I like thinking back to those days a lot.<\/p>\n<h4>\u2013 D.\u2028, 03.10.2008<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>20Hello Dana,\u2028 since the 03.11.I have been working as a clerk in the Neatherlands. .\u2028I enjoy my job as well as working with my colleagues, who support me whereever needed. The English course was for me beneficial, too, since I use it in my job, both in spoken and even more so written form.\u00a0 I [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-242","post","type-post","status-publish","format-standard","hentry","category-kundenmeinungen"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"20Hallo Dana, ich bin nun seit dem 03.11. als B\u00fcrokauffrau in den Niederlanden t\u00e4tig. Die Arbeit gef\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Twiety\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"dana von mach - wertevolle-kommunikation\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Stimme 20 - dana von mach\" \/>\n\t\t<meta property=\"og:description\" content=\"20Hallo Dana, ich bin nun seit dem 03.11. als B\u00fcrokauffrau in den Niederlanden t\u00e4tig. Die Arbeit gef\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-02-17T14:48:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-04T14:02:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Stimme 20 - dana von mach\" \/>\n\t\t<meta name=\"twitter:description\" content=\"20Hallo Dana, ich bin nun seit dem 03.11. als B\u00fcrokauffrau in den Niederlanden t\u00e4tig. Die Arbeit gef\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#blogposting\",\"name\":\"Stimme 20 - dana von mach\",\"headline\":\"Stimme 20\",\"author\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/author\\\/twiety\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/#organization\"},\"datePublished\":\"2011-02-17T14:48:35+00:00\",\"dateModified\":\"2026-07-04T14:02:53+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#webpage\"},\"articleSection\":\"Kundenmeinungen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.danavonmach.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.danavonmach.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/category\\\/kundenmeinungen\\\/#listItem\",\"name\":\"Kundenmeinungen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/category\\\/kundenmeinungen\\\/#listItem\",\"position\":2,\"name\":\"Kundenmeinungen\",\"item\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/category\\\/kundenmeinungen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#listItem\",\"name\":\"Stimme 20\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.danavonmach.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#listItem\",\"position\":3,\"name\":\"Stimme 20\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/category\\\/kundenmeinungen\\\/#listItem\",\"name\":\"Kundenmeinungen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/#organization\",\"name\":\"dana von mach\",\"description\":\"wertevolle-kommunikation\",\"url\":\"https:\\\/\\\/www.danavonmach.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/author\\\/twiety\\\/#author\",\"url\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/author\\\/twiety\\\/\",\"name\":\"Twiety\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9708a86bdf05e1180b4ce10f442f0a1403423c156bc011439639e3260da5c6e5?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Twiety\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#webpage\",\"url\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/\",\"name\":\"Stimme 20 - dana von mach\",\"description\":\"20Hallo Dana, ich bin nun seit dem 03.11. als B\\u00fcrokauffrau in den Niederlanden t\\u00e4tig. Die Arbeit gef\\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/2011\\\/02\\\/17\\\/stimme-20\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/author\\\/twiety\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/en\\\/blog\\\/author\\\/twiety\\\/#author\"},\"datePublished\":\"2011-02-17T14:48:35+00:00\",\"dateModified\":\"2026-07-04T14:02:53+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/#website\",\"url\":\"https:\\\/\\\/www.danavonmach.de\\\/\",\"name\":\"dana von mach\",\"description\":\"wertevolle-kommunikation\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.danavonmach.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Stimme 20 - dana von mach","description":"20Hallo Dana, ich bin nun seit dem 03.11. als B\u00fcrokauffrau in den Niederlanden t\u00e4tig. Die Arbeit gef\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir","canonical_url":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#blogposting","name":"Stimme 20 - dana von mach","headline":"Stimme 20","author":{"@id":"https:\/\/www.danavonmach.de\/en\/blog\/author\/twiety\/#author"},"publisher":{"@id":"https:\/\/www.danavonmach.de\/#organization"},"datePublished":"2011-02-17T14:48:35+00:00","dateModified":"2026-07-04T14:02:53+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#webpage"},"isPartOf":{"@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#webpage"},"articleSection":"Kundenmeinungen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.danavonmach.de#listItem","position":1,"name":"Home","item":"https:\/\/www.danavonmach.de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.danavonmach.de\/en\/blog\/category\/kundenmeinungen\/#listItem","name":"Kundenmeinungen"}},{"@type":"ListItem","@id":"https:\/\/www.danavonmach.de\/en\/blog\/category\/kundenmeinungen\/#listItem","position":2,"name":"Kundenmeinungen","item":"https:\/\/www.danavonmach.de\/en\/blog\/category\/kundenmeinungen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#listItem","name":"Stimme 20"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.danavonmach.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#listItem","position":3,"name":"Stimme 20","previousItem":{"@type":"ListItem","@id":"https:\/\/www.danavonmach.de\/en\/blog\/category\/kundenmeinungen\/#listItem","name":"Kundenmeinungen"}}]},{"@type":"Organization","@id":"https:\/\/www.danavonmach.de\/#organization","name":"dana von mach","description":"wertevolle-kommunikation","url":"https:\/\/www.danavonmach.de\/"},{"@type":"Person","@id":"https:\/\/www.danavonmach.de\/en\/blog\/author\/twiety\/#author","url":"https:\/\/www.danavonmach.de\/en\/blog\/author\/twiety\/","name":"Twiety","image":{"@type":"ImageObject","@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9708a86bdf05e1180b4ce10f442f0a1403423c156bc011439639e3260da5c6e5?s=96&d=mm&r=g","width":96,"height":96,"caption":"Twiety"}},{"@type":"WebPage","@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#webpage","url":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/","name":"Stimme 20 - dana von mach","description":"20Hallo Dana, ich bin nun seit dem 03.11. als B\u00fcrokauffrau in den Niederlanden t\u00e4tig. Die Arbeit gef\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.danavonmach.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/#breadcrumblist"},"author":{"@id":"https:\/\/www.danavonmach.de\/en\/blog\/author\/twiety\/#author"},"creator":{"@id":"https:\/\/www.danavonmach.de\/en\/blog\/author\/twiety\/#author"},"datePublished":"2011-02-17T14:48:35+00:00","dateModified":"2026-07-04T14:02:53+00:00"},{"@type":"WebSite","@id":"https:\/\/www.danavonmach.de\/#website","url":"https:\/\/www.danavonmach.de\/","name":"dana von mach","description":"wertevolle-kommunikation","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.danavonmach.de\/#organization"}}]},"og:locale":"en_US","og:site_name":"dana von mach - wertevolle-kommunikation","og:type":"article","og:title":"Stimme 20 - dana von mach","og:description":"20Hallo Dana, ich bin nun seit dem 03.11. als B\u00fcrokauffrau in den Niederlanden t\u00e4tig. Die Arbeit gef\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir","og:url":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/","article:published_time":"2011-02-17T14:48:35+00:00","article:modified_time":"2026-07-04T14:02:53+00:00","twitter:card":"summary_large_image","twitter:title":"Stimme 20 - dana von mach","twitter:description":"20Hallo Dana, ich bin nun seit dem 03.11. als B\u00fcrokauffrau in den Niederlanden t\u00e4tig. Die Arbeit gef\u00e4llt mir sehr gut und auch meine Kollegen sind alle sehr nett und helfen wo es geht. Der Englischkurs hat sich f\u00fcr mich auch sehr gelohnt, da ich teilweise auch Englisch sprechen, aber mehr schreiben muss. Der Kurs hat mir"},"aioseo_meta_data":{"post_id":"242","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-08 11:55:26","updated":"2026-07-08 11:55:26"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.danavonmach.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.danavonmach.de\/en\/blog\/category\/kundenmeinungen\/\" title=\"Kundenmeinungen\">Kundenmeinungen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tStimme 20\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.danavonmach.de"},{"label":"Kundenmeinungen","link":"https:\/\/www.danavonmach.de\/en\/blog\/category\/kundenmeinungen\/"},{"label":"Stimme 20","link":"https:\/\/www.danavonmach.de\/en\/blog\/2011\/02\/17\/stimme-20\/"}],"_links":{"self":[{"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/posts\/242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/comments?post=242"}],"version-history":[{"count":11,"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/posts\/242\/revisions"}],"predecessor-version":[{"id":1727,"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/posts\/242\/revisions\/1727"}],"wp:attachment":[{"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/media?parent=242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/categories?post=242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.danavonmach.de\/wp-json\/wp\/v2\/tags?post=242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}